{"id":180236,"date":"2026-05-30T00:21:46","date_gmt":"2026-05-29T22:21:46","guid":{"rendered":"https:\/\/crazycarsmoviepark.com\/note-legali\/"},"modified":"2026-07-09T02:47:36","modified_gmt":"2026-07-09T00:47:36","slug":"note-legali","status":"publish","type":"page","link":"https:\/\/crazycarsmoviepark.com\/it\/note-legali\/","title":{"rendered":"Note legali"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;482284&#8243;][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_image=&#8221;711&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; mobile_height=&#8221;340&#8243; uncode_shortcode_id=&#8221;197818&#8243;][\/vc_column][vc_column column_width_use_pixel=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; column_width_pixel=&#8221;528&#8243; uncode_shortcode_id=&#8221;476193&#8243;][vc_custom_heading text_color=&#8221;accent&#8221; heading_semantic=&#8221;h6&#8243; text_size=&#8221;h6&#8243; text_transform=&#8221;uppercase&#8221; uncode_shortcode_id=&#8221;768672&#8243; text_color_type=&#8221;uncode-palette&#8221;]Note legali[\/vc_custom_heading][vc_custom_heading text_size=&#8221;&#8221; uncode_shortcode_id=&#8221;934262&#8243;]Siamo contenti che tu voglia saperne di pi\u00f9![\/vc_custom_heading][vc_column_text text_lead=&#8221;yes&#8221; uncode_shortcode_id=&#8221;154674&#8243;]Il Crazy Cars Moviepark \u00e8 uno spettacolare evento dal vivo a Funtana, in Croazia, che unisce sport motoristici, commedia, personaggi in stile cinematografico, veicoli speciali, acrobazie e divertimento per tutta la famiglia. Le date dei nostri spettacoli sono pensate per famiglie, turisti in vacanza, gruppi e appassionati di azione che cercano un\u2019esperienza serale indimenticabile in Istria.[\/vc_column_text][vc_empty_space empty_h=&#8221;1&#8243;][vc_row_inner limit_content=&#8221;&#8221;][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;4&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243;][vc_custom_heading heading_semantic=&#8221;h3&#8243; text_size=&#8221;h4&#8243; subheading=&#8221;Insieme possiamo attirare pi\u00f9 attenzione, creare pi\u00f9 entusiasmo e regalare serate ancora pi\u00f9 indimenticabili. Se sei un hotel, un campeggio, un operatore turistico, un\u2019azienda locale o un marchio che si rivolge a un pubblico interessato alla famiglia o al turismo, non esitare a contattarci per presentarci la tua proposta. &#8221; uncode_shortcode_id=&#8221;152621&#8243;]Cerchiamo collaborazioni![\/vc_custom_heading][vc_button size=&#8221;btn-link&#8221; custom_typo=&#8221;yes&#8221; font_family=&#8221;font-555555&#8243; font_weight=&#8221;800&#8243; italic=&#8221;yes&#8221; icon_position=&#8221;right&#8221; scale_mobile=&#8221;no&#8221; icon=&#8221;fa fa-arrow-right4&#8243; link=&#8221;url:mailto%3Ainfo%40crazycarsmoviepark.com|target:_blank|&#8221; uncode_shortcode_id=&#8221;286123&#8243;]Invia un&#8217;e-mail[\/vc_button][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;4&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243;][vc_custom_heading heading_semantic=&#8221;h3&#8243; text_size=&#8221;h4&#8243; subheading=&#8221;Rendi la serata del tuo gruppo davvero speciale! Scuole, societ\u00e0 sportive, gruppi di viaggio, campeggi, hotel, associazioni e organizzazioni sono invitati a contattarci per informazioni sulle date degli spettacoli, pacchetti per gruppi e opzioni di visita speciali. Creiamo insieme un\u2019esperienza dal vivo indimenticabile!  &#8221; uncode_shortcode_id=&#8221;474881&#8243;]Organizzazioni e gruppi: benvenuti![\/vc_custom_heading][vc_button size=&#8221;btn-link&#8221; custom_typo=&#8221;yes&#8221; font_family=&#8221;font-555555&#8243; font_weight=&#8221;800&#8243; italic=&#8221;yes&#8221; icon_position=&#8221;right&#8221; scale_mobile=&#8221;no&#8221; icon=&#8221;fa fa-arrow-right4&#8243; link=&#8221;url:mailto%3Ainfo%40crazycarsmoviepark.com|target:_blank|&#8221; uncode_shortcode_id=&#8221;286123&#8243;]Invia un&#8217;e-mail[\/vc_button][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-130196&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;736264&#8243; back_color_type=&#8221;uncode-palette&#8221;][vc_column width=&#8221;1\/1&#8243;][vc_custom_heading uncode_shortcode_id=&#8221;609551&#8243;]Note legali[\/vc_custom_heading][vc_column_text uncode_shortcode_id=&#8221;528913&#8243;]<\/p>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-WEB:c1497d84-4abc-4ab3-9526-8c61b653a5bb-28\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:c1497d84-4abc-4ab3-9526-8c61b653a5bb-28\" data-turn-id-container=\"request-WEB:c1497d84-4abc-4ab3-9526-8c61b653a5bb-28\" data-testid=\"conversation-turn-6\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"528748c4-29d6-4ea7-9111-e5218f61ed76\" data-message-model-slug=\"gpt-5-5-thinking\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\n<p data-start=\"1040\" data-end=\"1101\">Note legali relative al Crazy Cars Moviepark (CROSS CONCEPT d.o.o.):<\/p>\n<p data-start=\"1103\" data-end=\"1158\"><strong data-start=\"1103\" data-end=\"1158\">Informazioni sulla societ\u00e0 ai sensi del diritto commerciale croato:<\/strong><\/p>\n<p data-start=\"1160\" data-end=\"1252\">CROSS CONCEPT, societ\u00e0 a responsabilit\u00e0 limitata specializzata in eventi di intrattenimento e parchi a tema<\/p>\n<p data-start=\"1254\" data-end=\"1265\">Istarska 16<\/p>\n<p data-start=\"1267\" data-end=\"1280\">52440 Funtana<\/p>\n<p data-start=\"1282\" data-end=\"1289\">Croazia<\/p>\n<p data-start=\"1291\" data-end=\"1309\">Forma giuridica: d.o.o.<\/p>\n<p data-start=\"1311\" data-end=\"1327\">OIB: 27677907183<\/p>\n<p data-start=\"1329\" data-end=\"1343\">MBS: 130141673<\/p>\n<p data-start=\"1345\" data-end=\"1357\">MB: 05778930<\/p>\n<p data-start=\"1359\" data-end=\"1392\">Data di costituzione: 19.05.2023<\/p>\n<p data-start=\"1394\" data-end=\"1435\">Tribunale di registrazione: Tribunale commerciale di Pazin<\/p>\n<p data-start=\"1437\" data-end=\"1461\"><strong data-start=\"1437\" data-end=\"1461\">Informazioni di contatto:<\/strong><\/p>\n<p data-start=\"1463\" data-end=\"1502\">Email: info [at] crazycarsmoviepark.com<\/p>\n<p data-start=\"1504\" data-end=\"1534\"><strong data-start=\"1504\" data-end=\"1534\">Risoluzione delle controversie online:<\/strong><\/p>\n<p data-start=\"1536\" data-end=\"1687\">La Commissione Europea mette a disposizione una piattaforma per la risoluzione delle controversie online (ODR): <a class=\"decorated-link\" href=\"https:\/\/ec.europa.eu\/consumers\/odr\" target=\"_new\" rel=\"noopener\" data-start=\"1615\" data-end=\"1649\">https:\/\/ec.europa.eu\/consumers\/odr<\/a>. Il nostro indirizzo e-mail \u00e8 indicato qui sopra. <\/p>\n<p data-start=\"1689\" data-end=\"1795\">Non siamo obbligati a partecipare alle procedure di risoluzione delle controversie dinanzi a un collegio arbitrale per i consumatori.<\/p>\n<p data-start=\"1797\" data-end=\"1819\"><strong data-start=\"1797\" data-end=\"1819\">Responsabilit\u00e0 sui contenuti:<\/strong><\/p>\n<p data-start=\"1821\" data-end=\"2074\">In qualit\u00e0 di fornitore di servizi, siamo responsabili dei nostri contenuti su queste pagine secondo le leggi vigenti. Tuttavia, non siamo obbligati a monitorare le informazioni esterne trasmesse o memorizzate, n\u00e9 a indagare su circostanze che indichino attivit\u00e0 illegali. <\/p>\n<p data-start=\"2076\" data-end=\"2349\">Gli obblighi di rimuovere o bloccare l&#8217;uso delle informazioni previsti dalle leggi generali rimangono invariati. Tuttavia, la responsabilit\u00e0 in tal senso sussiste solo a partire dal momento in cui si viene a conoscenza di una violazione specifica. Una volta ricevuta la segnalazione di tali violazioni, provvederemo a rimuovere immediatamente tali contenuti.  <\/p>\n<p data-start=\"2351\" data-end=\"2370\"><strong data-start=\"2351\" data-end=\"2370\">Responsabilit\u00e0 per i link:<\/strong><\/p>\n<p data-start=\"2372\" data-end=\"2794\">La nostra offerta include link a siti web esterni di terze parti, sui cui contenuti non abbiamo alcun controllo. Pertanto, non possiamo assumerci alcuna responsabilit\u00e0 per questi contenuti esterni. La responsabilit\u00e0 dei contenuti delle pagine collegate spetta sempre al rispettivo fornitore o gestore delle pagine stesse. Al momento della creazione del collegamento, le pagine collegate sono state controllate per verificare la presenza di eventuali violazioni della legge. Al momento della creazione del collegamento non erano riconoscibili contenuti illegali.    <\/p>\n<p data-start=\"2796\" data-end=\"2992\">Un monitoraggio costante dei contenuti delle pagine collegate non \u00e8 ragionevole in assenza di prove concrete di una violazione della legge. Non appena veniamo a conoscenza di eventuali violazioni, provvederemo a rimuovere immediatamente tali link. <\/p>\n<p data-start=\"2994\" data-end=\"3008\"><strong data-start=\"2994\" data-end=\"3008\">Copyright:<\/strong><\/p>\n<p data-start=\"3010\" data-end=\"3369\">I contenuti e le opere create dai gestori del sito in queste pagine sono soggetti alla legge croata sul diritto d&#8217;autore. La riproduzione, l&#8217;elaborazione, la distribuzione e qualsiasi tipo di utilizzo al di fuori dei limiti previsti dalla legge sul diritto d&#8217;autore richiedono il consenso scritto del rispettivo autore o creatore. Il download e la copia di questo sito sono consentiti esclusivamente per uso privato e non commerciale.  <\/p>\n<p data-start=\"3371\" data-end=\"3706\" data-is-last-node=\"\" data-is-only-node=\"\">Se i contenuti di questo sito non sono stati creati dal gestore, i diritti d&#8217;autore di terzi vengono rispettati. In particolare, i contenuti di terzi sono chiaramente identificati come tali. Se dovessi comunque riscontrare una violazione del diritto d&#8217;autore, ti preghiamo di segnalarcelo. Non appena riceveremo la segnalazione, provvederemo a rimuovere immediatamente tali contenuti.   <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<div class=\"pointer-events-none -mt-px h-px translate-y-[calc(var(--scroll-root-safe-area-inset-bottom)-14*var(--spacing))]\" aria-hidden=\"true\"><\/div>\n<p>[\/vc_column_text][vc_empty_space empty_h=&#8221;5&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;482284&#8243;][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_image=&#8221;711&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"two_page_speed":[],"footnotes":""},"class_list":["post-180236","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Note legali - Crazy Cars Movie Park<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crazycarsmoviepark.com\/it\/note-legali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Note legali - Crazy Cars Movie Park\" \/>\n<meta property=\"og:description\" content=\"[vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;482284&#8243;][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_image=&#8221;711&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crazycarsmoviepark.com\/it\/note-legali\/\" \/>\n<meta property=\"og:site_name\" content=\"Crazy Cars Movie Park\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CrazyCarsMoviepark\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T00:47:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/note-legali\\\/\",\"url\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/note-legali\\\/\",\"name\":\"Note legali - Crazy Cars Movie Park\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/#website\"},\"datePublished\":\"2026-05-29T22:21:46+00:00\",\"dateModified\":\"2026-07-09T00:47:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/note-legali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/note-legali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/note-legali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Note legali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/\",\"name\":\"Crazy Cars Movie Park\",\"description\":\"Experience the best live event in Croatia with your entire family. \",\"publisher\":{\"@id\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/#organization\",\"name\":\"Crazy Cars Movie Park\",\"url\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Crazy-Cars-Moviepark-Logo-transparent-small.png\",\"contentUrl\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Crazy-Cars-Moviepark-Logo-transparent-small.png\",\"width\":350,\"height\":199,\"caption\":\"Crazy Cars Movie Park\"},\"image\":{\"@id\":\"https:\\\/\\\/crazycarsmoviepark.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CrazyCarsMoviepark\",\"https:\\\/\\\/www.instagram.com\\\/crazycarsmoviepark\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Note legali - Crazy Cars Movie Park","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crazycarsmoviepark.com\/it\/note-legali\/","og_locale":"it_IT","og_type":"article","og_title":"Note legali - Crazy Cars Movie Park","og_description":"[vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;482284&#8243;][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_image=&#8221;711&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]","og_url":"https:\/\/crazycarsmoviepark.com\/it\/note-legali\/","og_site_name":"Crazy Cars Movie Park","article_publisher":"https:\/\/www.facebook.com\/CrazyCarsMoviepark","article_modified_time":"2026-07-09T00:47:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/crazycarsmoviepark.com\/it\/note-legali\/","url":"https:\/\/crazycarsmoviepark.com\/it\/note-legali\/","name":"Note legali - Crazy Cars Movie Park","isPartOf":{"@id":"https:\/\/crazycarsmoviepark.com\/it\/#website"},"datePublished":"2026-05-29T22:21:46+00:00","dateModified":"2026-07-09T00:47:36+00:00","breadcrumb":{"@id":"https:\/\/crazycarsmoviepark.com\/it\/note-legali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crazycarsmoviepark.com\/it\/note-legali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/crazycarsmoviepark.com\/it\/note-legali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/crazycarsmoviepark.com\/it\/"},{"@type":"ListItem","position":2,"name":"Note legali"}]},{"@type":"WebSite","@id":"https:\/\/crazycarsmoviepark.com\/it\/#website","url":"https:\/\/crazycarsmoviepark.com\/it\/","name":"Crazy Cars Movie Park","description":"Experience the best live event in Croatia with your entire family. ","publisher":{"@id":"https:\/\/crazycarsmoviepark.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crazycarsmoviepark.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/crazycarsmoviepark.com\/it\/#organization","name":"Crazy Cars Movie Park","url":"https:\/\/crazycarsmoviepark.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/crazycarsmoviepark.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/crazycarsmoviepark.com\/wp-content\/uploads\/2023\/01\/Crazy-Cars-Moviepark-Logo-transparent-small.png","contentUrl":"https:\/\/crazycarsmoviepark.com\/wp-content\/uploads\/2023\/01\/Crazy-Cars-Moviepark-Logo-transparent-small.png","width":350,"height":199,"caption":"Crazy Cars Movie Park"},"image":{"@id":"https:\/\/crazycarsmoviepark.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CrazyCarsMoviepark","https:\/\/www.instagram.com\/crazycarsmoviepark\/"]}]}},"_links":{"self":[{"href":"https:\/\/crazycarsmoviepark.com\/it\/wp-json\/wp\/v2\/pages\/180236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crazycarsmoviepark.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/crazycarsmoviepark.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/crazycarsmoviepark.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/crazycarsmoviepark.com\/it\/wp-json\/wp\/v2\/comments?post=180236"}],"version-history":[{"count":3,"href":"https:\/\/crazycarsmoviepark.com\/it\/wp-json\/wp\/v2\/pages\/180236\/revisions"}],"predecessor-version":[{"id":180239,"href":"https:\/\/crazycarsmoviepark.com\/it\/wp-json\/wp\/v2\/pages\/180236\/revisions\/180239"}],"wp:attachment":[{"href":"https:\/\/crazycarsmoviepark.com\/it\/wp-json\/wp\/v2\/media?parent=180236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}